{"id":1877,"date":"2016-05-02T09:03:40","date_gmt":"2016-05-02T07:03:40","guid":{"rendered":"http:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6.jpg"},"modified":"2016-05-02T09:03:40","modified_gmt":"2016-05-02T07:03:40","slug":"bild-6","status":"inherit","type":"attachment","link":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/blog\/2016\/05\/02\/im-sonnenuntergang-in-die-hamburger-hafencity\/bild-6\/","title":{"rendered":"Bild (6)"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1877","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-300x225.jpg 300w, https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-1024x768.jpg 1024w, https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-400x300.jpg 400w, https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6.jpg 1632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1632,"height":1224,"file":"2016\/05\/Bild-6.jpg","sizes":{"thumbnail":{"file":"Bild-6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-150x150.jpg"},"medium":{"file":"Bild-6-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-300x225.jpg"},"large":{"file":"Bild-6-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-1024x768.jpg"},"post-thumbnail":{"file":"Bild-6-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-1000x288.jpg"},"large-feature":{"file":"Bild-6-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-1000x288.jpg"},"small-feature":{"file":"Bild-6-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6-400x300.jpg"},"full":{"file":"Bild-6.jpg","width":1632,"height":1224,"mime_type":"image\/jpeg","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6.jpg"}},"image_meta":{"aperture":2.2,"credit":"","camera":"iPhone 6","caption":"","created_timestamp":1462099011,"copyright":"","focal_length":"4.15","iso":"32","shutter_speed":"0.00035398230088496","title":"","orientation":1}},"post":1870,"source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2016\/05\/Bild-6.jpg","_links":{"self":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/media\/1877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/users\/3"}]}}