{"id":2150,"date":"2017-05-29T23:19:28","date_gmt":"2017-05-29T21:19:28","guid":{"rendered":"http:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1.png"},"modified":"2017-05-29T23:19:28","modified_gmt":"2017-05-29T21:19:28","slug":"image7-1-2","status":"inherit","type":"attachment","link":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/blog\/2017\/05\/29\/novomind-meets-stormvogel\/image7-1-2\/","title":{"rendered":"image7-1"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2150","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"300\" src=\"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-180x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-180x300.png 180w, https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1.png 768w, https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-614x1024.png 614w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":768,"height":1280,"file":"2017\/05\/image7-1.png","sizes":{"thumbnail":{"file":"image7-1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-150x150.png"},"medium":{"file":"image7-1-180x300.png","width":180,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-180x300.png"},"medium_large":{"file":"image7-1-768x1280.png","width":768,"height":1280,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-768x1280.png"},"large":{"file":"image7-1-614x1024.png","width":614,"height":1024,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-614x1024.png"},"post-thumbnail":{"file":"image7-1-768x288.png","width":768,"height":288,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-768x288.png"},"large-feature":{"file":"image7-1-768x288.png","width":768,"height":288,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-768x288.png"},"small-feature":{"file":"image7-1-180x300.png","width":180,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1-180x300.png"},"full":{"file":"image7-1.png","width":768,"height":1280,"mime_type":"image\/png","source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2143,"source_url":"https:\/\/www.diemel-net.de\/_wp_s6ibl0g\/wp-content\/uploads\/2017\/05\/image7-1.png","_links":{"self":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/media\/2150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.diemel-net.de\/Knuts-Segel-Touren\/wp-json\/wp\/v2\/types\/attachment"}]}}